{"id":181,"date":"2017-01-19T21:20:56","date_gmt":"2017-01-19T20:20:56","guid":{"rendered":"http:\/\/imorche.de\/blog\/?p=181"},"modified":"2017-01-31T22:31:32","modified_gmt":"2017-01-31T21:31:32","slug":"a-j-kazinski-todestrank","status":"publish","type":"post","link":"http:\/\/imorche.de\/blog\/2017\/01\/19\/a-j-kazinski-todestrank\/","title":{"rendered":"A. J. Kazinski &#8211; Todestrank"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-182\" src=\"http:\/\/imorche.de\/blog\/wp-content\/uploads\/2017\/01\/61pVQTXEY0L._SL150_.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"http:\/\/imorche.de\/blog\/wp-content\/uploads\/2017\/01\/61pVQTXEY0L._SL150_.jpg 150w, http:\/\/imorche.de\/blog\/wp-content\/uploads\/2017\/01\/61pVQTXEY0L._SL150_-50x50.jpg 50w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/p>\n<p><em><span class=\"adbl-date adbl-release-date\">Erschienen: 01.09.2016<\/span><\/em><\/p>\n<p><em>Anbieter: Random House<\/em><\/p>\n<p><em>Sprecher: David Nathan<\/em><\/p>\n<p><em>Wertung: keine<\/em><\/p>\n<p><strong>Alberner Reinkarnationskram<\/strong><\/p>\n<p>Keine Wertung, weil ich nach ca. der H\u00e4lfte aufgeh\u00f6rt und das H\u00f6rbuch zur\u00fcckgegeben habe. Superermittler begibt sich undercover in eine Irrenanstalt f\u00fcr Schwerverbrecher und kann da schon am zweiten Tage schalten und walten, sein Ex-Freundin ist Forscherin und l\u00f6st mal eben auf dem Weg nach S\u00fcdamerika, auf einer lange geplanten Dienstreise, ein kryptographisches R\u00e4tsel und stellt dann auf eigene Faust Ermittlungen an, so eine Art weiblicher Indiana Jones, dann noch ein 65 Jahre alter Todesfall, der irgendwie in die Gegenwart reicht, mit Wiederauferstehung und so, jede Menge Logik-Fehler und irgendwann hatte ich genug davon&#8230;<\/p>\n<p>Seit die skandinavischen Ermittler alle zu Superm\u00e4nnern mutiert sind, mag man gar keinen nordischen Krimi mehr anfassen. Wo sind sie nur geblieben, Martin Beck, Kurt Wallander, van Veeteren, Erik Winter.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erschienen: 01.09.2016 Anbieter: Random House Sprecher: David Nathan Wertung: keine Alberner Reinkarnationskram Keine Wertung, weil ich nach ca. der H\u00e4lfte aufgeh\u00f6rt und das H\u00f6rbuch zur\u00fcckgegeben habe. Superermittler begibt sich undercover in eine Irrenanstalt f\u00fcr Schwerverbrecher und kann da schon am zweiten Tage schalten und walten, sein Ex-Freundin ist Forscherin und l\u00f6st mal eben auf dem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/imorche.de\/blog\/wp-json\/wp\/v2\/posts\/181"}],"collection":[{"href":"http:\/\/imorche.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/imorche.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/imorche.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/imorche.de\/blog\/wp-json\/wp\/v2\/comments?post=181"}],"version-history":[{"count":2,"href":"http:\/\/imorche.de\/blog\/wp-json\/wp\/v2\/posts\/181\/revisions"}],"predecessor-version":[{"id":184,"href":"http:\/\/imorche.de\/blog\/wp-json\/wp\/v2\/posts\/181\/revisions\/184"}],"wp:attachment":[{"href":"http:\/\/imorche.de\/blog\/wp-json\/wp\/v2\/media?parent=181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/imorche.de\/blog\/wp-json\/wp\/v2\/categories?post=181"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/imorche.de\/blog\/wp-json\/wp\/v2\/tags?post=181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}